{"id":29542,"date":"2026-04-29T01:23:27","date_gmt":"2026-04-29T04:23:27","guid":{"rendered":"https:\/\/piermaua.rio\/evento\/ab2l-lawtech-experience-2026\/"},"modified":"2026-04-29T01:25:19","modified_gmt":"2026-04-29T04:25:19","slug":"ab2l-lawtech-experience-2026","status":"publish","type":"tribe_events","link":"https:\/\/piermaua.rio\/en\/evento\/ab2l-lawtech-experience-2026\/","title":{"rendered":"AB2L Lawtech Experience 2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[13],"class_list":["post-29542","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-evento","cat_evento"],"acf":[],"_links":{"self":[{"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/tribe_events\/29542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/tribe_events\/29542\/revisions"}],"predecessor-version":[{"id":29566,"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/tribe_events\/29542\/revisions\/29566"}],"wp:attachment":[{"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/media?parent=29542"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/tags?post=29542"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/piermaua.rio\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=29542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}